{"id":19808,"date":"2021-03-31T12:05:17","date_gmt":"2021-03-31T09:05:17","guid":{"rendered":"https:\/\/www.yilmazmachine.com.tr\/urunler\/dc-550-pb-double-head-mitre-saw-machines\/"},"modified":"2026-07-02T17:15:48","modified_gmt":"2026-07-02T14:15:48","slug":"dc-550-pb-troncatrice-doppia-testa-automatica","status":"publish","type":"urunler","link":"https:\/\/www.yilmazmachine.com.tr\/it\/prodotti\/dc-550-pb-troncatrice-doppia-testa-automatica\/","title":{"rendered":"DC 550 PB &#8211;  TRONCATRICE DOPPIA TESTA AUTOMATICA"},"content":{"rendered":"<p>DC 550 PB \u00e8 una segatrice completamente automatica progettata per le operazioni di taglio rettilineo o angolare di profili di grandi dimensioni in PVC e alluminio per mezzo di unit\u00e0 di taglio a doppia testa dotate di lame di \u00d8 550 mm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DC 550 PB \u00e8 una segatrice completamente automatica progettata per le operazioni di taglio rettilineo o angolare di profili di grandi dimensioni in PVC e alluminio per mezzo di unit\u00e0 di taglio a doppia testa dotate di lame di \u00d8 550 mm.<\/p>\n","protected":false},"author":2,"featured_media":70757,"template":"","urun_kategori":[2471,2474,2470],"class_list":["post-19808","urunler","type-urunler","status-publish","has-post-thumbnail","hentry","urun_kategori-taglio-a-doppia-testa","urun_kategori-alluminio-it","urun_kategori-taglio-a-sega"],"acf":[],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"extra":{"gallery":[],"categories":["TAGLIO A DOPPIA TESTA","ALLUMINIO","TAGLIO A SEGA"],"technical":[{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/elektrik.png","spec":"6.9 kW  400V AC 3P+PE \/ 50\/60 Hz."},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/profil.png","spec":""},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/freze.png","spec":"2.400 RPM"},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/freze2.png","spec":""},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/kose_pres.png","spec":""},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/cerceve.png","spec":""},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/vidalama.png","spec":""},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/testere-donus.png","spec":"2400 RPM "},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/testere-cap.png","spec":"D: \u00d8550 mm<br \/>\nd: \u00d830-32 mm"},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/basinc.png","spec":"200 L\/min"},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/basinc.png","spec":"6-8 bar"},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/boyutlar.png","spec":"185x509x172"},{"image":"https:\/\/www.yilmazmachine.com.tr\/wp-content\/themes\/yilmazmachine\/assets\/img\/picto_app\/agirlik.png","spec":"1.280 Kg Kg \/ 1.444 Kg Kg"}],"catalogue":false,"consumption":{"debi":"200","en":"185","boy":"509","yukseklik":"172","kw":"6.9","amper":0,"agirlik":"1.280 ","elektrik":"400V AC 3P+PE \/ 50\/60 Hz."}},"_links":{"self":[{"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/urunler\/19808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/urunler"}],"about":[{"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/types\/urunler"}],"author":[{"embeddable":true,"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":3,"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/urunler\/19808\/revisions"}],"predecessor-version":[{"id":87911,"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/urunler\/19808\/revisions\/87911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/media\/70757"}],"wp:attachment":[{"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/media?parent=19808"}],"wp:term":[{"taxonomy":"urun_kategori","embeddable":true,"href":"https:\/\/www.yilmazmachine.com.tr\/it\/wp-json\/wp\/v2\/urun_kategori?post=19808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}